{"id":912,"date":"2024-06-10T17:47:12","date_gmt":"2024-06-10T17:47:12","guid":{"rendered":"https:\/\/kasbahlesportesdudesert.com\/rooms\/suite-quadruple\/"},"modified":"2024-07-07T10:04:50","modified_gmt":"2024-07-07T10:04:50","slug":"suite-quadruple","status":"publish","type":"rooms","link":"https:\/\/kasbahlesportesdudesert.com\/fr\/rooms\/suite-quadruple\/","title":{"rendered":"Suite quadruple"},"content":{"rendered":"\n<p>Id\u00e9ale pour les familles ou les groupes, cette suite spacieuse comprend un coin salon, une terrasse priv\u00e9e, la climatisation, une connexion Wi-Fi gratuite et une salle de bains privative.<\/p>\n","protected":false},"featured_media":824,"template":"","type-room":[48],"amenities":[51,55,69,54,52,53,56],"class_list":["post-912","rooms","type-rooms","status-publish","has-post-thumbnail","hentry","type-room-suite-fr","amenities-climatiseur","amenities-douche","amenities-petit-dejeuner","amenities-refrigerateur","amenities-salle-de-bain","amenities-tv-cablee","amenities-wifi-fr"],"_links":{"self":[{"href":"https:\/\/kasbahlesportesdudesert.com\/fr\/wp-json\/wp\/v2\/rooms\/912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kasbahlesportesdudesert.com\/fr\/wp-json\/wp\/v2\/rooms"}],"about":[{"href":"https:\/\/kasbahlesportesdudesert.com\/fr\/wp-json\/wp\/v2\/types\/rooms"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kasbahlesportesdudesert.com\/fr\/wp-json\/wp\/v2\/media\/824"}],"wp:attachment":[{"href":"https:\/\/kasbahlesportesdudesert.com\/fr\/wp-json\/wp\/v2\/media?parent=912"}],"wp:term":[{"taxonomy":"type-room","embeddable":true,"href":"https:\/\/kasbahlesportesdudesert.com\/fr\/wp-json\/wp\/v2\/type-room?post=912"},{"taxonomy":"amenities","embeddable":true,"href":"https:\/\/kasbahlesportesdudesert.com\/fr\/wp-json\/wp\/v2\/amenities?post=912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}